{"id":2117,"date":"2021-02-03T14:05:31","date_gmt":"2021-02-03T14:05:31","guid":{"rendered":"https:\/\/horlewire.com\/?p=2117"},"modified":"2021-02-03T14:05:31","modified_gmt":"2021-02-03T14:05:31","slug":"huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet","status":"publish","type":"post","link":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/","title":{"rendered":"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d!"},"content":{"rendered":"<p>Huesecken Wire GmbH ist sich seiner gesellschaftlichen Verantwortung als Unternehmen bewusst und m\u00f6chte dieser gerecht werden. Aus diesem Grund wurden bereits in der Vergangenheit einige Schritte eingeleitet, um den Standort in Hohenlimburg vor dem Aspekt der Nachhaltigkeit besser aufzustellen und neben sozialen und \u00f6konomischen Interessen auch \u00f6kologische Ziele effizient zu verfolgen.<\/p>\n<p>Neben einem ganzheitlichen Energiemanagement, welches nach DIN EN 50001 zertifiziert ist, sowie der Anschaffung eines erdgasbetriebenen PKW f\u00fcr Dienstfahrten zwischen den Werken, sollen nun auch im Verwaltungsbereich weitere Umstellungen erfolgen. Das Ziel ist es, auf lange Sicht ein \u201dpapierloses B\u00fcro\u201d zu erm\u00f6glichen. Daf\u00fcr wurden intern bereits einige Ma\u00dfnahmen umgesetzt und weitere Projekte befinden sich in der Planungsphase. Die hierbei verfolgten Ans\u00e4tze beziehen sich auf elektronische Notizb\u00fccher, den Aufbau eines digitalen Dokumentenworkflows sowie die Planung einer EDI-Anbindung f\u00fcr Kunden und Lieferanten. Wichtige Unterlagen, bei welchen sich ein Ausdruck nicht vermeiden l\u00e4sst, werden doppelseitig gedruckt. Dadurch konnte das Papieraufkommen in der Verwaltung bereits erheblich gesenkt werden.<\/p>\n<p>F\u00fcr weitere Einsparungen wurden im Dezember 2020 die Gesch\u00e4ftspartner der Huesecken Wire GmbH mit der Bitte kontaktiert, die entsprechenden Mail-Adressen zum elektronischen Empfang regelm\u00e4\u00dfig anfallender Dokumente wie Rechnungen oder Pr\u00fcfzeugnisse an Huesecken zu kommunizieren. Positive Resonanz, Bereitschaft zur Unterst\u00fctzung und ein schnelles Feedback der Kunden und Lieferanten sorgten daf\u00fcr, dass ein Gro\u00dfteil des Dokumentenaustauschs auf digitalen Versand und Empfang umgestellt werden konnte. Mit den durch die Umstellungen eingesparten Kosten f\u00fcr Porto, Briefb\u00f6gen, Briefumschl\u00e4ge etc. wird die Stiftung \u201dPlant-for-the-Planet\u201d <a href=\"https:\/\/a.plant-for-the-planet.org\/de\/\"><strong>https:\/\/a.plant-for-the-planet.org\/de\/<\/strong><\/a>\u00a0unterst\u00fctzt .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Huesecken Wire GmbH ist sich seiner gesellschaftlichen Verantwortung als Unternehmen bewusst und m\u00f6chte dieser gerecht werden. Aus diesem Grund wurden bereits in der Vergangenheit einige Schritte eingeleitet, um den Standort in Hohenlimburg vor dem Aspekt der Nachhaltigkeit besser aufzustellen und neben sozialen und \u00f6konomischen Interessen auch \u00f6kologische Ziele effizient zu verfolgen. Neben einem ganzheitlichen Energiemanagement, &#8230;<\/p>\n","protected":false},"author":2,"featured_media":2095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d! - H\u00f6rle Wire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d! - H\u00f6rle Wire\" \/>\n<meta property=\"og:description\" content=\"Huesecken Wire GmbH ist sich seiner gesellschaftlichen Verantwortung als Unternehmen bewusst und m\u00f6chte dieser gerecht werden. Aus diesem Grund wurden bereits in der Vergangenheit einige Schritte eingeleitet, um den Standort in Hohenlimburg vor dem Aspekt der Nachhaltigkeit besser aufzustellen und neben sozialen und \u00f6konomischen Interessen auch \u00f6kologische Ziele effizient zu verfolgen. Neben einem ganzheitlichen Energiemanagement, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00f6rle Wire\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-03T14:05:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/horlewire.com\/wp-content\/uploads\/2021\/02\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Horle_Wire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Horle_Wire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/\"},\"author\":{\"name\":\"Horle_Wire\",\"@id\":\"https:\\\/\\\/horlewire.com\\\/sk\\\/#\\\/schema\\\/person\\\/8ab8ebd9cfd8dfc36b4217072348be3d\"},\"headline\":\"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d!\",\"datePublished\":\"2021-02-03T14:05:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/\"},\"wordCount\":274,\"image\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/horlewire.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/\",\"url\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/\",\"name\":\"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d! - H\u00f6rle Wire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/sk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/horlewire.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg\",\"datePublished\":\"2021-02-03T14:05:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/sk\\\/#\\\/schema\\\/person\\\/8ab8ebd9cfd8dfc36b4217072348be3d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/horlewire.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg\",\"contentUrl\":\"https:\\\/\\\/horlewire.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/horlewire.com\\\/de\\\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/horlewire.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/horlewire.com\\\/sk\\\/#website\",\"url\":\"https:\\\/\\\/horlewire.com\\\/sk\\\/\",\"name\":\"H\u00f6rle Wire\",\"description\":\"Welcome to H\u00f6rle Wire Group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/horlewire.com\\\/sk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/horlewire.com\\\/sk\\\/#\\\/schema\\\/person\\\/8ab8ebd9cfd8dfc36b4217072348be3d\",\"name\":\"Horle_Wire\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hrle-wire-group\\\/?viewAsMember=true\"],\"url\":\"https:\\\/\\\/horlewire.com\\\/de\\\/author\\\/horle_wire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d! - H\u00f6rle Wire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/","og_locale":"de_DE","og_type":"article","og_title":"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d! - H\u00f6rle Wire","og_description":"Huesecken Wire GmbH ist sich seiner gesellschaftlichen Verantwortung als Unternehmen bewusst und m\u00f6chte dieser gerecht werden. Aus diesem Grund wurden bereits in der Vergangenheit einige Schritte eingeleitet, um den Standort in Hohenlimburg vor dem Aspekt der Nachhaltigkeit besser aufzustellen und neben sozialen und \u00f6konomischen Interessen auch \u00f6kologische Ziele effizient zu verfolgen. Neben einem ganzheitlichen Energiemanagement, ...","og_url":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/","og_site_name":"H\u00f6rle Wire","article_published_time":"2021-02-03T14:05:31+00:00","og_image":[{"width":700,"height":400,"url":"https:\/\/horlewire.com\/wp-content\/uploads\/2021\/02\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg","type":"image\/jpeg"}],"author":"Horle_Wire","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Horle_Wire","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/#article","isPartOf":{"@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/"},"author":{"name":"Horle_Wire","@id":"https:\/\/horlewire.com\/sk\/#\/schema\/person\/8ab8ebd9cfd8dfc36b4217072348be3d"},"headline":"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d!","datePublished":"2021-02-03T14:05:31+00:00","mainEntityOfPage":{"@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/"},"wordCount":274,"image":{"@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/#primaryimage"},"thumbnailUrl":"https:\/\/horlewire.com\/wp-content\/uploads\/2021\/02\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/","url":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/","name":"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d! - H\u00f6rle Wire","isPartOf":{"@id":"https:\/\/horlewire.com\/sk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/#primaryimage"},"image":{"@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/#primaryimage"},"thumbnailUrl":"https:\/\/horlewire.com\/wp-content\/uploads\/2021\/02\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg","datePublished":"2021-02-03T14:05:31+00:00","author":{"@id":"https:\/\/horlewire.com\/sk\/#\/schema\/person\/8ab8ebd9cfd8dfc36b4217072348be3d"},"breadcrumb":{"@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/#primaryimage","url":"https:\/\/horlewire.com\/wp-content\/uploads\/2021\/02\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg","contentUrl":"https:\/\/horlewire.com\/wp-content\/uploads\/2021\/02\/Nachhaltigkeit-Unternehmen-1091624174-700-003.jpg","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/horlewire.com\/de\/huesecken-wire-geht-erste-schritte-zum-papierlosen-buero-und-unterstuetzt-plant-for-the-planet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/horlewire.com\/de\/"},{"@type":"ListItem","position":2,"name":"Huesecken Wire geht erste Schritte zum \u201dpapierlosen B\u00fcro\u201d und unterst\u00fctzt \u201dPlant for the Planet\u201d!"}]},{"@type":"WebSite","@id":"https:\/\/horlewire.com\/sk\/#website","url":"https:\/\/horlewire.com\/sk\/","name":"H\u00f6rle Wire","description":"Welcome to H\u00f6rle Wire Group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/horlewire.com\/sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/horlewire.com\/sk\/#\/schema\/person\/8ab8ebd9cfd8dfc36b4217072348be3d","name":"Horle_Wire","sameAs":["https:\/\/www.linkedin.com\/company\/hrle-wire-group\/?viewAsMember=true"],"url":"https:\/\/horlewire.com\/de\/author\/horle_wire\/"}]}},"_links":{"self":[{"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/posts\/2117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/comments?post=2117"}],"version-history":[{"count":2,"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/posts\/2117\/revisions"}],"predecessor-version":[{"id":2119,"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/posts\/2117\/revisions\/2119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/media\/2095"}],"wp:attachment":[{"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/media?parent=2117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/categories?post=2117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/horlewire.com\/de\/wp-json\/wp\/v2\/tags?post=2117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}